{"id":102872,"date":"2026-04-10T03:49:36","date_gmt":"2026-04-10T06:49:36","guid":{"rendered":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/"},"modified":"2026-04-10T03:49:41","modified_gmt":"2026-04-10T06:49:41","slug":"fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia","status":"publish","type":"post","link":"https:\/\/ubirataonline.com.br\/en\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/","title":{"rendered":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas &#8211; 09\/04\/2026 &#8211; Economia"},"content":{"rendered":"<p><\/p>\n<div data-news-content-text=\"\" data-disable-copy=\"\" data-continue-reading=\"\" data-continue-reading-hide-others=\".js-continue-reading-hidden\" data-age-rating=\"\" itemprop=\"articleBody\">\n<p>O governo de Luiz In\u00e1cio <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/lula\/\">Lula<\/a> da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/fgts\/\">FGTS<\/a> (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de dar aos trabalhadores condi\u00e7\u00f5es de reduzir seu endividamento \u2014uma das <a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2026\/03\/lula-diz-que-povo-culpa-governo-por-endividamento-e-que-pediu-solucao-a-fazenda.shtml\" rel=\"\" target=\"\">preocupa\u00e7\u00f5es centrais do petista em ano eleitoral<\/a>.<\/p>\n<p>Uma das medidas vai destravar <a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2026\/04\/governo-lula-quer-liberar-r-7-bilhoes-do-fgts-em-medida-para-reduzir-endividamento.shtml\">cerca de R$ 7 bilh\u00f5es<\/a> que ficaram parados como garantia em opera\u00e7\u00f5es de antecipa\u00e7\u00e3o do saque-anivers\u00e1rio.<\/p>\n<p>A segunda iniciativa vai prever a possibilidade de um saque extraordin\u00e1rio para os trabalhadores, mas apenas para pagar d\u00edvidas.<\/p>\n<p>Segundo uma pessoa que participa das discuss\u00f5es, a ideia \u00e9 permitir o uso do recurso para abater d\u00edvidas mais caras, como rotativo do cart\u00e3o de cr\u00e9dito, que estejam em dia ou atrasadas. Outro interlocutor afirma que o dinheiro seria liberado diretamente para o credor do d\u00e9bito, com o objetivo de efetivamente reduzir o comprometimento de renda dessas fam\u00edlias. Detalhes como valores e demais regras para o saque ainda est\u00e3o em discuss\u00e3o.<\/p>\n<p>O saque extraordin\u00e1rio do FGTS seria uma medida complementar \u00e0 linha de cr\u00e9dito que as fam\u00edlias poder\u00e3o acessar para renegociar suas d\u00edvidas com taxas de juros mais baixas, gra\u00e7as \u00e0 garantia do governo por meio do FGO (Fundo Garantidor de Opera\u00e7\u00f5es), que honrar\u00e1 os pagamentos em caso de inadimpl\u00eancia. Na linha com FGO, por\u00e9m, apenas as d\u00edvidas em atraso devem ser alvo de negocia\u00e7\u00e3o.<\/p>\n<p>Na ter\u00e7a-feira (7), o ministro <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/dario-durigan\/\">Dario Durigan<\/a> (Fazenda) disse que o <a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2026\/04\/governo-prepara-linhas-de-credito-para-dividas-de-pessoas-fisicas-mei-e-pequenas-empresas-diz-ministro.shtml\" rel=\"\" target=\"\">governo estava estudando o impacto<\/a> do uso dos recursos do FGTS para a sustentabilidade do fundo. &#8220;Estamos caminhando com essa avalia\u00e7\u00e3o do impacto. Isso ainda n\u00e3o est\u00e1 conclu\u00eddo&#8221;, afirmou na ocasi\u00e3o.<\/p>\n<p>J\u00e1 nesta quinta-feira (9), o ministro <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/luiz-marinho\/\">Luiz Marinho<\/a> (Trabalho) disse ao <a href=\"https:\/\/radios.ebc.com.br\/alo-alo-brasil\/2026\/04\/alo-alo-brasil-recebe-luiz-marinho-ministro-do-trabalho-e-emprego-que-fala\" target=\"_blank\">programa Al\u00f4 Al\u00f4 Brasil<\/a>, da R\u00e1dio Nacional, que a libera\u00e7\u00e3o dos R$ 7 bilh\u00f5es travados pela antecipa\u00e7\u00e3o do saque-anivers\u00e1rio pode beneficiar cerca de 10 milh\u00f5es de trabalhadores.<\/p>\n<p>Segundo um t\u00e9cnico do governo, um entendimento da <a href=\"https:\/\/www1.folha.uol.com.br\/folha-topicos\/caixa-economica-federal\/\">Caixa Econ\u00f4mica Federal<\/a> levou a um bloqueio maior nas contas dos trabalhadores para assegurar o pagamento dos empr\u00e9stimos vinculados ao saque-anivers\u00e1rio no futuro. Agora, deve prevalecer a interpreta\u00e7\u00e3o do governo, que v\u00ea necessidade de uma reten\u00e7\u00e3o menor e, consequentemente, espa\u00e7o para liberar novos recursos.<\/p>\n<p>Um parecer jur\u00eddico poderia dar respaldo ao entendimento do governo, segundo uma autoridade ouvida pela <b>Folha<\/b> sob reserva. Mas parte dos t\u00e9cnicos ainda v\u00ea necessidade de mudan\u00e7a legal para dar seguran\u00e7a \u00e0 medida.<\/p>\n<p>A controv\u00e9rsia gira em torno dos valores que ficam retidos nas contas do FGTS dos trabalhadores que optaram pelo saque-anivers\u00e1rio e anteciparam as parcelas dos pr\u00f3ximos anos por meio de opera\u00e7\u00f5es de cr\u00e9dito.<\/p>\n<p>A lei autoriza que a Caixa, agente operador do fundo, fa\u00e7a o bloqueio do valor necess\u00e1rio para cobrir no futuro os pagamentos das presta\u00e7\u00f5es devidas \u00e0s institui\u00e7\u00f5es financeiras e que ser\u00e3o quitadas com o saque-anivers\u00e1rio do trabalhador naquele ano.<\/p>\n<p>Pela legisla\u00e7\u00e3o, o valor do saque corresponde a uma fra\u00e7\u00e3o de 5% a 50% do saldo total nas contas do trabalhador no FGTS, mais uma parcela fixa. Por isso, a Caixa bloqueia o saldo requerido para que o saque decorrente deste c\u00e1lculo seja suficiente para quitar as presta\u00e7\u00f5es.<\/p>\n<p>No fim do ano passado, o governo editou a MP (medida provis\u00f3ria) 1.331 e liberou o fundo de garantia para trabalhadores que aderiram ao saque-anivers\u00e1rio e n\u00e3o puderam resgatar o saldo total quando foram demitidos sem justa causa (at\u00e9 dezembro de 2025), mas a Caixa manteve a interpreta\u00e7\u00e3o.<\/p>\n<p>A institui\u00e7\u00e3o segurou um saldo maior dos trabalhadores que haviam contratado as antecipa\u00e7\u00f5es, seguindo o racioc\u00ednio de que o saque que vai cobrir o pagamento das opera\u00e7\u00f5es de cr\u00e9dito \u00e9 apenas uma fra\u00e7\u00e3o do valor na conta.<\/p>\n<p>O entendimento do governo, por\u00e9m, \u00e9 de que a Caixa deveria ter retido apenas o valor exato das parcelas futuras, com base no texto da pr\u00f3pria MP, que fala em manuten\u00e7\u00e3o da &#8220;totalidade das garantias compromissadas&#8221;.<\/p>\n<p>Segundo um t\u00e9cnico, \u00e9 essa interpreta\u00e7\u00e3o que vai prevalecer agora. Como ficar\u00e3o retidos apenas os valores suficientes para honrar os empr\u00e9stimos j\u00e1 devidos no futuro por esses trabalhadores, cerca de R$ 7 bilh\u00f5es ficar\u00e3o dispon\u00edveis para resgate.<\/p>\n<p>Em um exemplo hipot\u00e9tico, pelas regras do saque-anivers\u00e1rio, um trabalhador com saldo de R$ 2.000 em conta pode resgatar R$ 750 em seu anivers\u00e1rio (30% do saldo mais uma parcela fixa de R$ 150, conforme as regras aplic\u00e1veis a essa faixa de saldo no fundo).<\/p>\n<p>Se no passado ele antecipou esse valor numa opera\u00e7\u00e3o de cr\u00e9dito, isso significa que a Caixa bloqueou n\u00e3o s\u00f3 os R$ 750 devidos \u00e0 institui\u00e7\u00e3o financeira, mas os R$ 2.000 de saldo necess\u00e1rios para que o c\u00e1lculo do saque resulte em valor suficiente para quitar o empr\u00e9stimo.<\/p>\n<p>O que o governo quer \u00e9, neste exemplo hipot\u00e9tico, manter o bloqueio de R$ 750 e liberar os outros R$ 1.250 para o trabalhador.<\/p>\n<p>Na entrevista \u00e0 R\u00e1dio Nacional, Marinho chegou a atribuir a quest\u00e3o a um &#8220;erro&#8221; da Caixa.<\/p>\n<p>&#8220;A Caixa cometeu um erro porque n\u00e3o liberou a totalidade desses recursos, ent\u00e3o tem um res\u00edduo de R$ 7 bilh\u00f5es que n\u00f3s estamos trabalhando e propondo que libere agora&#8221;, disse.<\/p>\n<p>Procurada, a Caixa disse observar estritamente a legisla\u00e7\u00e3o vigente e seguir as determina\u00e7\u00f5es do Conselho Curador do FGTS, \u00f3rg\u00e3o com representa\u00e7\u00e3o de empresas, trabalhadores e governo respons\u00e1vel por definir as pol\u00edticas de uso do fundo.<\/p>\n<p>A modalidade saque-anivers\u00e1rio foi criada em 2019 pelo governo Jair Bolsonaro (PL). Ao optar pelo modelo, o trabalhador pode sacar uma parte do FGTS anualmente, no m\u00eas do seu anivers\u00e1rio. Mas ele abre m\u00e3o de poder retirar todo o saldo que acumulou ao ser demitido, ficando apenas com a multa rescis\u00f3ria de 40%.<\/p>\n<p>Em fevereiro e dezembro de 2025, o governo Lula editou medidas provis\u00f3rias liberando o saque completo do saldo do FGTS para quem havia sido demitido sem justa causa entre janeiro de 2020 e dezembro de 2025.<\/p>\n<p>Com a primeira medida, o governo previa <a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2025\/03\/veja-quanto-o-trabalhador-recebera-no-saque-aniversario-do-fgts.shtml\">liberar R$ 12 bilh\u00f5es para 12 milh\u00f5es de trabalhadores<\/a>, e com a segunda, R$ 7,8 bilh\u00f5es para 14 milh\u00f5es de trabalhadores. Ficariam retidos apenas os valores usados como garantia nas antecipa\u00e7\u00f5es do saque-anivers\u00e1rio \u2013agora, alvos da controv\u00e9rsia.<\/p>\n<p>&#8220;O regramento aplic\u00e1vel aos valores bloqueados em garantia decorrentes das opera\u00e7\u00f5es vinculadas ao saque-anivers\u00e1rio do FGTS \u00e9 definido pelo Conselho Curador do FGTS, de acordo com a Lei n\u00ba 8.036\/1990&#8221;, disse a Caixa, em nota.<\/p>\n<p>O governo ainda estuda permitir o uso de parte do saldo do FGTS como garantia adicional no empr\u00e9stimo consignado, que j\u00e1 tem a folha de pagamento do trabalhador como garantia prim\u00e1ria \u2014as parcelas s\u00e3o descontadas diretamente do sal\u00e1rio. A avalia\u00e7\u00e3o dos t\u00e9cnicos envolvidos \u00e9 que a medida pode ajudar a reduzir as taxas de juros cobradas na modalidade.<\/p>\n<p>&#8220;[O trabalhador] poderia usar uma parcela para quitar a sua d\u00edvida. Ent\u00e3o, se ele disser: &#8216;topo pegar 10% do fundo mais a multa para dar de garantia para ter uma taxa de juros menor e baixar a presta\u00e7\u00e3o&#8217;, poderia&#8221;, disse Marinho, em entrevista ao <a href=\"https:\/\/oglobo.globo.com\/economia\/noticia\/2026\/04\/09\/entrevista-governo-vai-liberar-r-7-bi-do-fgts-a-10-milhoes-de-trabalhadores-diz-ministro-do-trabalho.ghtml\" rel=\"\" target=\"_blank\">jornal O Globo<\/a>.<\/p>\n<\/p><\/div>\n<p><a href=\"https:\/\/www1.folha.uol.com.br\/mercado\/2026\/04\/governo-lula-vai-autorizar-novos-saques-do-fgts-e-preve-liberar-ao-menos-r-7-bi.shtml\">Fonte do Artigo <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de dar aos trabalhadores condi\u00e7\u00f5es de reduzir seu endividamento \u2014uma das preocupa\u00e7\u00f5es centrais do petista em ano eleitoral. Uma das medidas vai destravar cerca de R$ 7 bilh\u00f5es que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":102873,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow2JLhCw:productID":"","_gspb_post_css":"","maa_idioma":"","maa_pais":"","footnotes":""},"categories":[4],"tags":[4543,1898,115,1646,3987,2904,8231,26404,21261],"class_list":["post-102872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-dividas","tag-economia","tag-fgts","tag-governo","tag-novos","tag-para","tag-preve","tag-quitar","tag-saques"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\/04\/2026 - Economia - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!<\/title>\n<meta name=\"description\" content=\"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ubirataonline.com.br\/en\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\/04\/2026 - Economia\" \/>\n<meta property=\"og:description\" content=\"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ubirataonline.com.br\/en\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-10T06:49:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T06:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/ubirataonline\" \/>\n<meta name=\"twitter:site\" content=\"@ubirataonline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/\"},\"author\":{\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\"},\"headline\":\"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas &#8211; 09\\\/04\\\/2026 &#8211; Economia\",\"datePublished\":\"2026-04-10T06:49:36+00:00\",\"dateModified\":\"2026-04-10T06:49:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/\"},\"wordCount\":1242,\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg\",\"keywords\":[\"d\u00edvidas\",\"economia\",\"FGTS\",\"Governo\",\"novos\",\"para\",\"prev\u00ea\",\"quitar\",\"saques\"],\"articleSection\":[\"Brasil\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/\",\"name\":\"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\\\/04\\\/2026 - Economia - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg\",\"datePublished\":\"2026-04-10T06:49:36+00:00\",\"dateModified\":\"2026-04-10T06:49:41+00:00\",\"description\":\"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg\",\"width\":2400,\"height\":1600,\"caption\":\"Movimenta\u00e7\u00e3o em ag\u00eancia da Caixa em SP no ano passado, no primeiro dia de saques do FGTS para quem tinha saque-anivers\u00e1rio bloqueado - Zanone Fraissat - 6.mar.25\\\/Folhapress\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ubirataonline.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas &#8211; 09\\\/04\\\/2026 &#8211; Economia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"description\":\"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"alternateName\":\"Ubirat\u00e3 Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ubirataonline.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"alternateName\":\"Ubirat\u00e3 Online\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/x.com\\\/ubirataonline\",\"https:\\\/\\\/mastodon.social\\\/@ubirataonline\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/311144672285604\",\"https:\\\/\\\/www.facebook.com\\\/UBTAOnline\",\"https:\\\/\\\/www.instagram.com\\\/portalubirataonline\\\/\",\"https:\\\/\\\/twitter.com\\\/ubirataonline\"],\"description\":\"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.\",\"legalName\":\"UBIRATA ONLINE NOT\u00cdCIAS\",\"foundingDate\":\"2009-01-05\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/ubirataonline.com.br\\\/faq\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"-24.5361401\",\"longitude\":\"-52.9921776\"},\"telephone\":[\"+5544998308235\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"contato@ubirataonline.com.br\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"contato@ubirataonline.com.br\",\"vatID\":\"47.621.418\\\/0001-80\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\",\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"pronouns\":\"Ele\",\"description\":\"Desde 2003 trabalhando com not\u00edcias.\",\"sameAs\":[\"http:\\\/\\\/ubirataoline.com.br\",\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/www.instagram.com\\\/ubirataonline_oficial\",\"https:\\\/\\\/x.com\\\/x.com\\\/ubirataonline\"],\"honorificPrefix\":\"Mr.\",\"honorificSuffix\":\"MD\",\"birthDate\":\"1980-06-16\",\"gender\":\"masculino\",\"award\":[\"V\u00e1rios pr\u00eamios de melhor portal da cidade\"],\"jobTitle\":\"Diretor\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/author\\\/ubirataonline\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#local-main-place-address\",\"streetAddress\":\"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista\",\"addressLocality\":\"UBIRATA\",\"postalCode\":\"85440-000\",\"addressRegion\":\"PR\",\"addressCountry\":\"BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"width\":500,\"height\":500,\"caption\":\"Ubirat\u00e3 Online Not\u00edcias\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"UBIRATA\" \/>\n<meta name=\"geo.position\" content=\"-24.5361401;-52.9921776\" \/>\n<meta name=\"geo.region\" content=\"Brazil\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\/04\/2026 - Economia - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","description":"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ubirataonline.com.br\/en\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/","og_locale":"en_US","og_type":"article","og_title":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\/04\/2026 - Economia","og_description":"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de","og_url":"https:\/\/ubirataonline.com.br\/en\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/","og_site_name":"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","article_publisher":"https:\/\/www.facebook.com\/portalubirataonline","article_author":"https:\/\/www.facebook.com\/portalubirataonline","article_published_time":"2026-04-10T06:49:36+00:00","article_modified_time":"2026-04-10T06:49:41+00:00","og_image":[{"width":2400,"height":1600,"url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg","type":"image\/jpeg"}],"author":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","twitter_card":"summary_large_image","twitter_creator":"@x.com\/ubirataonline","twitter_site":"@ubirataonline","twitter_misc":{"Written by":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#article","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/"},"author":{"name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c"},"headline":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas &#8211; 09\/04\/2026 &#8211; Economia","datePublished":"2026-04-10T06:49:36+00:00","dateModified":"2026-04-10T06:49:41+00:00","mainEntityOfPage":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/"},"wordCount":1242,"publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"image":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg","keywords":["d\u00edvidas","economia","FGTS","Governo","novos","para","prev\u00ea","quitar","saques"],"articleSection":["Brasil"],"inLanguage":"en-US","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/ubirataonline.com.br\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/","url":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/","name":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas - 09\/04\/2026 - Economia - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#primaryimage"},"image":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg","datePublished":"2026-04-10T06:49:36+00:00","dateModified":"2026-04-10T06:49:41+00:00","description":"O governo de Luiz In\u00e1cio Lula da Silva (PT) prepara dois mecanismos de libera\u00e7\u00e3o extra do FGTS (Fundo de Garantia do Tempo de Servi\u00e7o), numa tentativa de","breadcrumb":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#primaryimage","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/FGTS-governo-preve-novos-saques-para-quitar-dividas-09042026.jpg","width":2400,"height":1600,"caption":"Movimenta\u00e7\u00e3o em ag\u00eancia da Caixa em SP no ano passado, no primeiro dia de saques do FGTS para quem tinha saque-anivers\u00e1rio bloqueado - Zanone Fraissat - 6.mar.25\/Folhapress"},{"@type":"BreadcrumbList","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ubirataonline.com.br\/"},{"@type":"ListItem","position":2,"name":"FGTS: governo prev\u00ea novos saques para quitar d\u00edvidas &#8211; 09\/04\/2026 &#8211; Economia"}]},{"@type":"WebSite","@id":"https:\/\/ubirataonline.com.br\/#website","url":"https:\/\/ubirataonline.com.br\/","name":"Ubirat\u00e3 Online Not\u00edcias","description":"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.","publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"alternateName":"Ubirat\u00e3 Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ubirataonline.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/ubirataonline.com.br\/#organization","name":"Ubirat\u00e3 Online Not\u00edcias","alternateName":"Ubirat\u00e3 Online","url":"https:\/\/ubirataonline.com.br\/","logo":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#local-main-organization-logo"},"image":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/portalubirataonline","https:\/\/x.com\/ubirataonline","https:\/\/mastodon.social\/@ubirataonline","https:\/\/www.facebook.com\/groups\/311144672285604","https:\/\/www.facebook.com\/UBTAOnline","https:\/\/www.instagram.com\/portalubirataonline\/","https:\/\/twitter.com\/ubirataonline"],"description":"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.","legalName":"UBIRATA ONLINE NOT\u00cdCIAS","foundingDate":"2009-01-05","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/ubirataonline.com.br\/faq\/","address":{"@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"-24.5361401","longitude":"-52.9921776"},"telephone":["+5544998308235"],"contactPoint":{"@type":"ContactPoint","email":"contato@ubirataonline.com.br"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"contato@ubirataonline.com.br","vatID":"47.621.418\/0001-80"},{"@type":"Person","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c","name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","pronouns":"Ele","description":"Desde 2003 trabalhando com not\u00edcias.","sameAs":["http:\/\/ubirataoline.com.br","https:\/\/www.facebook.com\/portalubirataonline","https:\/\/www.instagram.com\/ubirataonline_oficial","https:\/\/x.com\/x.com\/ubirataonline"],"honorificPrefix":"Mr.","honorificSuffix":"MD","birthDate":"1980-06-16","gender":"masculino","award":["V\u00e1rios pr\u00eamios de melhor portal da cidade"],"jobTitle":"Diretor","url":"https:\/\/ubirataonline.com.br\/en\/author\/ubirataonline\/"},{"@type":"PostalAddress","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#local-main-place-address","streetAddress":"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista","addressLocality":"UBIRATA","postalCode":"85440-000","addressRegion":"PR","addressCountry":"BR"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/fgts-governo-preve-novos-saques-para-quitar-dividas-09-04-2026-economia\/#local-main-organization-logo","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","width":500,"height":500,"caption":"Ubirat\u00e3 Online Not\u00edcias"}]},"geo.placename":"UBIRATA","geo.position":{"lat":"-24.5361401","long":"-52.9921776"},"geo.region":"Brazil"},"_links":{"self":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/102872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/comments?post=102872"}],"version-history":[{"count":0,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/102872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media\/102873"}],"wp:attachment":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media?parent=102872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/categories?post=102872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/tags?post=102872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}