{"id":116591,"date":"2026-04-27T08:22:53","date_gmt":"2026-04-27T11:22:53","guid":{"rendered":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/"},"modified":"2026-04-27T08:22:55","modified_gmt":"2026-04-27T11:22:55","slug":"pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie","status":"publish","type":"post","link":"https:\/\/ubirataonline.com.br\/en\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/","title":{"rendered":"Pai de Max Verstappen sofre acidente em Rally de Wallonie"},"content":{"rendered":"<p><\/p>\n<div id=\"texto\">\n<p>O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O carro do piloto saiu da pista e capotou, encerrando precocemente sua participa\u00e7\u00e3o.<\/p>\n<p>De acordo com a organiza\u00e7\u00e3o da prova, o ve\u00edculo de Verstappen ficou bastante danificado e chegou a parar de cabe\u00e7a para baixo ap\u00f3s o acidente, que foi confirmado oficialmente nas redes sociais do evento.<\/p>\n<p>Apesar da gravidade da situa\u00e7\u00e3o, Verstappen e seu copiloto, Jasper Vermeulen, n\u00e3o sofreram ferimentos.<\/p>\n<p>Nesta etapa, o piloto competia sem seu copiloto habitual, Renaud Jamoul, que est\u00e1 afastado ap\u00f3s fraturar o tornozelo durante a semana.<\/p>\n<p>Pai do tetracampe\u00e3o mundial de F\u00f3rmula 1, Max Verstappen, Jos havia encerrado o primeiro dia de competi\u00e7\u00e3o na terceira coloca\u00e7\u00e3o. No entanto, ainda no s\u00e1bado, recebeu uma penaliza\u00e7\u00e3o de 40 segundos por excesso de velocidade em um trecho de deslocamento, o que o derrubou para a 17\u00aa posi\u00e7\u00e3o antes do acidente deste domingo.<\/p>\n<\/p><\/div>\n<p><a href=\"https:\/\/cgn.inf.br\/noticia\/2093000\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\">Fonte do Artigo <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O carro do piloto saiu da pista e capotou, encerrando precocemente sua participa\u00e7\u00e3o. De acordo com a organiza\u00e7\u00e3o da prova, o ve\u00edculo de Verstappen ficou bastante danificado e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":116593,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow2JLhCw:productID":"","_gspb_post_css":"","maa_idioma":"","maa_pais":"","footnotes":""},"categories":[1],"tags":[26,5479,7288,13452,9184,6742,31487],"class_list":["post-116591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubirata","tag-acidente","tag-max","tag-pai","tag-rally","tag-sofre","tag-verstappen","tag-wallonie"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pai de Max Verstappen sofre acidente em Rally de Wallonie - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!<\/title>\n<meta name=\"description\" content=\"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ubirataonline.com.br\/en\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pai de Max Verstappen sofre acidente em Rally de Wallonie\" \/>\n<meta property=\"og:description\" content=\"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ubirataonline.com.br\/en\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/\" \/>\n<meta property=\"og:site_name\" content=\"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-27T11:22:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T11:22:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/ubirataonline\" \/>\n<meta name=\"twitter:site\" content=\"@ubirataonline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/\"},\"author\":{\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\"},\"headline\":\"Pai de Max Verstappen sofre acidente em Rally de Wallonie\",\"datePublished\":\"2026-04-27T11:22:53+00:00\",\"dateModified\":\"2026-04-27T11:22:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/\"},\"wordCount\":187,\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg\",\"keywords\":[\"Acidente\",\"Max\",\"pai\",\"rally\",\"sofre\",\"Verstappen\",\"Wallonie\"],\"articleSection\":[\"Ubirat\u00e3\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/\",\"name\":\"Pai de Max Verstappen sofre acidente em Rally de Wallonie - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg\",\"datePublished\":\"2026-04-27T11:22:53+00:00\",\"dateModified\":\"2026-04-27T11:22:55+00:00\",\"description\":\"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg\",\"width\":595,\"height\":335,\"caption\":\"Reprodu\u00e7\u00e3o: X\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ubirataonline.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pai de Max Verstappen sofre acidente em Rally de Wallonie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"description\":\"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"alternateName\":\"Ubirat\u00e3 Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ubirataonline.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"alternateName\":\"Ubirat\u00e3 Online\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/x.com\\\/ubirataonline\",\"https:\\\/\\\/mastodon.social\\\/@ubirataonline\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/311144672285604\",\"https:\\\/\\\/www.facebook.com\\\/UBTAOnline\",\"https:\\\/\\\/www.instagram.com\\\/portalubirataonline\\\/\",\"https:\\\/\\\/twitter.com\\\/ubirataonline\"],\"description\":\"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.\",\"legalName\":\"UBIRATA ONLINE NOT\u00cdCIAS\",\"foundingDate\":\"2009-01-05\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/ubirataonline.com.br\\\/faq\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"-24.5361401\",\"longitude\":\"-52.9921776\"},\"telephone\":[\"+5544998308235\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"contato@ubirataonline.com.br\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"contato@ubirataonline.com.br\",\"vatID\":\"47.621.418\\\/0001-80\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\",\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"pronouns\":\"Ele\",\"description\":\"Desde 2003 trabalhando com not\u00edcias.\",\"sameAs\":[\"http:\\\/\\\/ubirataoline.com.br\",\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/www.instagram.com\\\/ubirataonline_oficial\",\"https:\\\/\\\/x.com\\\/x.com\\\/ubirataonline\"],\"honorificPrefix\":\"Mr.\",\"honorificSuffix\":\"MD\",\"birthDate\":\"1980-06-16\",\"gender\":\"masculino\",\"award\":[\"V\u00e1rios pr\u00eamios de melhor portal da cidade\"],\"jobTitle\":\"Diretor\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/author\\\/ubirataonline\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#local-main-place-address\",\"streetAddress\":\"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista\",\"addressLocality\":\"UBIRATA\",\"postalCode\":\"85440-000\",\"addressRegion\":\"PR\",\"addressCountry\":\"BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"width\":500,\"height\":500,\"caption\":\"Ubirat\u00e3 Online Not\u00edcias\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"UBIRATA\" \/>\n<meta name=\"geo.position\" content=\"-24.5361401;-52.9921776\" \/>\n<meta name=\"geo.region\" content=\"Brazil\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pai de Max Verstappen sofre acidente em Rally de Wallonie - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","description":"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ubirataonline.com.br\/en\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/","og_locale":"en_US","og_type":"article","og_title":"Pai de Max Verstappen sofre acidente em Rally de Wallonie","og_description":"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O","og_url":"https:\/\/ubirataonline.com.br\/en\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/","og_site_name":"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","article_publisher":"https:\/\/www.facebook.com\/portalubirataonline","article_author":"https:\/\/www.facebook.com\/portalubirataonline","article_published_time":"2026-04-27T11:22:53+00:00","article_modified_time":"2026-04-27T11:22:55+00:00","og_image":[{"width":595,"height":335,"url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg","type":"image\/jpeg"}],"author":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","twitter_card":"summary_large_image","twitter_creator":"@x.com\/ubirataonline","twitter_site":"@ubirataonline","twitter_misc":{"Written by":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#article","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/"},"author":{"name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c"},"headline":"Pai de Max Verstappen sofre acidente em Rally de Wallonie","datePublished":"2026-04-27T11:22:53+00:00","dateModified":"2026-04-27T11:22:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/"},"wordCount":187,"publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"image":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg","keywords":["Acidente","Max","pai","rally","sofre","Verstappen","Wallonie"],"articleSection":["Ubirat\u00e3"],"inLanguage":"en-US","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/ubirataonline.com.br\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/","url":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/","name":"Pai de Max Verstappen sofre acidente em Rally de Wallonie - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#primaryimage"},"image":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg","datePublished":"2026-04-27T11:22:53+00:00","dateModified":"2026-04-27T11:22:55+00:00","description":"O ex-piloto de F\u00f3rmula 1 Jos Verstappen abandonou o Rally de Wallonie na manh\u00e3 de domingo (27) ap\u00f3s sofrer um acidente logo na primeira especial do dia. O","breadcrumb":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#primaryimage","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/04\/Pai-de-Max-Verstappen-sofre-acidente-em-Rally-de-Wallonie.jpg","width":595,"height":335,"caption":"Reprodu\u00e7\u00e3o: X"},{"@type":"BreadcrumbList","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ubirataonline.com.br\/"},{"@type":"ListItem","position":2,"name":"Pai de Max Verstappen sofre acidente em Rally de Wallonie"}]},{"@type":"WebSite","@id":"https:\/\/ubirataonline.com.br\/#website","url":"https:\/\/ubirataonline.com.br\/","name":"Ubirat\u00e3 Online Not\u00edcias","description":"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.","publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"alternateName":"Ubirat\u00e3 Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ubirataonline.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/ubirataonline.com.br\/#organization","name":"Ubirat\u00e3 Online Not\u00edcias","alternateName":"Ubirat\u00e3 Online","url":"https:\/\/ubirataonline.com.br\/","logo":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#local-main-organization-logo"},"image":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/portalubirataonline","https:\/\/x.com\/ubirataonline","https:\/\/mastodon.social\/@ubirataonline","https:\/\/www.facebook.com\/groups\/311144672285604","https:\/\/www.facebook.com\/UBTAOnline","https:\/\/www.instagram.com\/portalubirataonline\/","https:\/\/twitter.com\/ubirataonline"],"description":"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.","legalName":"UBIRATA ONLINE NOT\u00cdCIAS","foundingDate":"2009-01-05","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/ubirataonline.com.br\/faq\/","address":{"@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"-24.5361401","longitude":"-52.9921776"},"telephone":["+5544998308235"],"contactPoint":{"@type":"ContactPoint","email":"contato@ubirataonline.com.br"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"contato@ubirataonline.com.br","vatID":"47.621.418\/0001-80"},{"@type":"Person","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c","name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","pronouns":"Ele","description":"Desde 2003 trabalhando com not\u00edcias.","sameAs":["http:\/\/ubirataoline.com.br","https:\/\/www.facebook.com\/portalubirataonline","https:\/\/www.instagram.com\/ubirataonline_oficial","https:\/\/x.com\/x.com\/ubirataonline"],"honorificPrefix":"Mr.","honorificSuffix":"MD","birthDate":"1980-06-16","gender":"masculino","award":["V\u00e1rios pr\u00eamios de melhor portal da cidade"],"jobTitle":"Diretor","url":"https:\/\/ubirataonline.com.br\/en\/author\/ubirataonline\/"},{"@type":"PostalAddress","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#local-main-place-address","streetAddress":"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista","addressLocality":"UBIRATA","postalCode":"85440-000","addressRegion":"PR","addressCountry":"BR"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/pai-de-max-verstappen-sofre-acidente-em-rally-de-wallonie\/#local-main-organization-logo","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","width":500,"height":500,"caption":"Ubirat\u00e3 Online Not\u00edcias"}]},"geo.placename":"UBIRATA","geo.position":{"lat":"-24.5361401","long":"-52.9921776"},"geo.region":"Brazil"},"_links":{"self":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/116591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/comments?post=116591"}],"version-history":[{"count":0,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/116591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media\/116593"}],"wp:attachment":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media?parent=116591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/categories?post=116591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/tags?post=116591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}