{"id":123001,"date":"2026-05-07T00:54:21","date_gmt":"2026-05-07T03:54:21","guid":{"rendered":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/"},"modified":"2026-05-07T00:54:30","modified_gmt":"2026-05-07T03:54:30","slug":"toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf","status":"publish","type":"post","link":"https:\/\/ubirataonline.com.br\/en\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/","title":{"rendered":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf"},"content":{"rendered":"<p><br \/>\n<\/p>\n<div>\n<h2>Toluca enfrenta la &#8216;maldici\u00f3n&#8217; que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la Concacaf<\/h2>\n<hr\/>\n<p><strong><a href=\"https:\/\/espndeportes.espn.com\/futbol\/equipo\/_\/id\/223\/toluca\" target=\"_blank\">Toluca<\/a><\/strong> tropez\u00f3 en el primer juego de la serie de semifinales ante <strong>LAFC<\/strong> por un marcador de 2-1. Este resultado pone sobre la mesa una cuenta pendiente para los clubes mexicanos que, a pesar de llegar como bicampeones de la Liga MX, no han logrado trasladar ese dominio al plano regional.<\/p>\n<p><strong><a href=\"https:\/\/espndeportes.espn.com\/futbol\/equipo\/_\/id\/223\/toluca\" target=\"_blank\">Los Diablos<\/a><\/strong> afrontar\u00e1n el juego de vuelta en el <strong>Estadio Nemesio Diez<\/strong> con este antecedente, buscando romper la tendencia que ha sentenciado a otros equipos que llegaron a la Concacaf con la fuerza de un bicampeonato, pero fallaron al intentar ampliar su hegemon\u00eda internacional.<\/p>\n<p>El equipo universitario fue el primero en esta lista. Se present\u00f3 en la edici\u00f3n de 2005 tras ganar dos t\u00edtulos de liga de forma consecutiva. Aunque super\u00f3 al<strong> Olimpia<\/strong> y al <strong>DC United<\/strong>, en la final se enfrent\u00f3 al Saprissa. La derrota de 2-0 en el juego de ida pes\u00f3 demasiado y la reacci\u00f3n en Ciudad Universitaria fue insuficiente; el conjunto auriazul perdi\u00f3 la serie con un global de 3-2. Cabe destacar que Pumas ha sido el \u00fanico equipo mexicano en perder dos finales ante rivales de la zona.<\/p>\n<aside class=\"inline inline-photo full\">\n<figure><picture><source data-srcset=\"https:\/\/a1.espncdn.com\/combiner\/i?img=%2Fphoto%2F2026%2F0506%2Fr1654185_1296x729_16%2D9.jpg&amp;w=570&amp;format=jpg, https:\/\/a1.espncdn.com\/combiner\/i?img=%2Fphoto%2F2026%2F0506%2Fr1654185_1296x729_16%2D9.jpg&amp;w=1140&amp;cquality=40&amp;format=jpg 2x\" media=\"(min-width: 376px)\"><source data-srcset=\"https:\/\/a1.espncdn.com\/combiner\/i?img=%2Fphoto%2F2026%2F0506%2Fr1654185_1296x729_16%2D9.jpg&amp;w=375, https:\/\/a1.espncdn.com\/combiner\/i?img=%2Fphoto%2F2026%2F0506%2Fr1654185_1296x729_16%2D9.jpg&amp;w=750&amp;cquality=40&amp;format=jpg 2x\" media=\"(max-width: 375px)\"><img class=\"lazyload lazyload\" data-image-container=\".inline-photo\" height=\"320\" width=\"570\"\/><\/source><\/source><\/picture><figcaption class=\"photoCaption\">Toluca busca la final de la Concacaf Champions Cup ante LAFC.\u00a0<cite>AP<\/cite><\/figcaption><\/figure>\n<\/aside>\n<p><img decoding=\"async\" alt=\"LEO\" class=\"Image Logo Logo__sm\" data-mptype=\"image\" src=\"https:\/\/a.espncdn.com\/combiner\/i?img=\/i\/teamlogos\/soccer\/500\/228.png&amp;h=40&amp;w=40\" title=\"LEO\"\/><\/p>\n<p>La Fiera apareci\u00f3 diez a\u00f1os despu\u00e9s con una expectativa similar. El bicampe\u00f3n del futbol mexicano entr\u00f3 a la temporada 2014-2015 como uno de los favoritos, pero su participaci\u00f3n termin\u00f3 antes de lo previsto. <strong>Herediano<\/strong> y <strong>Metap\u00e1n<\/strong> lo dejaron fuera en la fase de grupos, un saldo pobre para un plantel que proyectaba un dominio mayor tras haber conquistado el balompi\u00e9 nacional. En sus cuatro juegos disputados, registraron dos triunfos, un empate y una derrota.<\/p>\n<aside class=\"inline editorial float-r\" data-behavior=\"article_related\">\n<h2 class=\"editorial-title\">Selecciones Editoriales<\/h2>\n<ul>\n<li><a name=\"&amp;lpos=story:editorspicks:inline:1\" href=\"https:\/\/espndeportes.espn.com\/futbol\/mexico\/nota\/_\/id\/16672015\/alexis-vega-jesus-gallardo-permiso-mexico-jugar-toluca-concacaf\" class=\"img-link\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/a.espncdn.com\/combiner\/i?img=\/photo\/2026\/0506\/r1654128_1296x1296_1-1.jpg&amp;w=130&amp;h=130&amp;scale=crop&amp;location=center\" width=\"65\" height=\"65\"\/><\/a><\/li>\n<\/ul>\n<\/aside>\n<p><img decoding=\"async\" alt=\"ATS\" class=\"Image Logo Logo__sm\" data-mptype=\"image\" src=\"https:\/\/a.espncdn.com\/combiner\/i?img=\/i\/teamlogos\/soccer\/500\/216.png&amp;h=40&amp;w=40\" title=\"ATS\"\/><\/p>\n<p>Los Rojinegros tambi\u00e9n intentaron romper esta secuencia en 2023. Sufrieron desde los octavos de final ante el Olimpia, avanzando con un global de 5-4, pero en la siguiente ronda se toparon con el <strong>Philadelphia Union<\/strong>. La derrota por la m\u00ednima en la ida condicion\u00f3 la serie, y el empate 2-2 en la vuelta sell\u00f3 su eliminaci\u00f3n.<\/p>\n<p><img decoding=\"async\" alt=\"AME\" class=\"Image Logo Logo__sm\" data-mptype=\"image\" src=\"https:\/\/a.espncdn.com\/combiner\/i?img=\/i\/teamlogos\/soccer\/500\/227.png&amp;h=40&amp;w=40\" title=\"AME\"\/><\/p>\n<p>La oportunidad m\u00e1s reciente hab\u00eda sido para las <strong>\u00c1guilas<\/strong>, m\u00e1ximos ganadores de este torneo. A pesar de su jerarqu\u00eda, el equipo suma ya una d\u00e9cada sin levantar el trofeo; en esta ocasi\u00f3n, se despidieron en los cuartos de final al caer 2-1 en el juego de vuelta.<\/p>\n<p>Ahora, el Toluca entra en este mismo escenario. Si bien la derrota en California no define la serie, vuelve a colocar al bicampe\u00f3n mexicano frente a una barrera hist\u00f3rica. Un factor determinante para la vuelta ser\u00e1 el gol de visitante, que sigue vigente en esta edici\u00f3n; las dos anotaciones recibidas obligar\u00e1n a los Diablos a ser impecables en defensa si pretenden hacer valer la local\u00eda en el <strong>Nemesio Diez<\/strong>.<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/espndeportes.espn.com\/futbol\/norte-centro-america\/nota\/_\/id\/16672568\/toluca-vs-lafc-semifinal-vuelta-concacaf-champions-cup\">Source link <\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Toluca enfrenta la &#8216;maldici\u00f3n&#8217; que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la Concacaf Toluca tropez\u00f3 en el primer juego de la serie de semifinales ante LAFC por un marcador de 2-1. Este resultado pone sobre la mesa una cuenta pendiente para los clubes mexicanos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":123002,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow2JLhCw:productID":"","_gspb_post_css":"","maa_idioma":"","maa_pais":"","footnotes":""},"categories":[1],"tags":[33544,6777,4191,33545,4111,14428],"class_list":["post-123001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ubirata","tag-bicampeones","tag-clubes","tag-concacaf","tag-ganan","tag-liga","tag-toluca"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Toluca: Clubes bicampeones de Liga MX no ganan Concacaf - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!<\/title>\n<meta name=\"description\" content=\"Toluca enfrenta la &#039;maldici\u00f3n&#039; que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ubirataonline.com.br\/en\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf\" \/>\n<meta property=\"og:description\" content=\"Toluca enfrenta la &#039;maldici\u00f3n&#039; que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ubirataonline.com.br\/en\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/\" \/>\n<meta property=\"og:site_name\" content=\"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T03:54:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T03:54:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/ubirataonline\" \/>\n<meta name=\"twitter:site\" content=\"@ubirataonline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/\"},\"author\":{\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\"},\"headline\":\"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf\",\"datePublished\":\"2026-05-07T03:54:21+00:00\",\"dateModified\":\"2026-05-07T03:54:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/\"},\"wordCount\":506,\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg\",\"keywords\":[\"bicampeones\",\"clubes\",\"Concacaf\",\"ganan\",\"liga\",\"Toluca\"],\"articleSection\":[\"Ubirat\u00e3\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/\",\"name\":\"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg\",\"datePublished\":\"2026-05-07T03:54:21+00:00\",\"dateModified\":\"2026-05-07T03:54:30+00:00\",\"description\":\"Toluca enfrenta la 'maldici\u00f3n' que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg\",\"width\":1296,\"height\":729,\"caption\":\"Mohamed revela que contar\u00e1 con Gallardo y Vega en la Concachampions (1:01)Alexis Vega y Jes\u00fas Gallardo podr\u00e1n jugar con Toluca el partido de vuelta de las semifinales de Concacaf Champions Cup ante LAFC, debido a que recibieron permiso de la Selecci\u00f3n Mexicana. (1:01)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ubirataonline.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"description\":\"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"alternateName\":\"Ubirat\u00e3 Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ubirataonline.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"alternateName\":\"Ubirat\u00e3 Online\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/x.com\\\/ubirataonline\",\"https:\\\/\\\/mastodon.social\\\/@ubirataonline\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/311144672285604\",\"https:\\\/\\\/www.facebook.com\\\/UBTAOnline\",\"https:\\\/\\\/www.instagram.com\\\/portalubirataonline\\\/\",\"https:\\\/\\\/twitter.com\\\/ubirataonline\"],\"description\":\"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.\",\"legalName\":\"UBIRATA ONLINE NOT\u00cdCIAS\",\"foundingDate\":\"2009-01-05\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/ubirataonline.com.br\\\/faq\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"-24.5361401\",\"longitude\":\"-52.9921776\"},\"telephone\":[\"+5544998308235\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"contato@ubirataonline.com.br\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"contato@ubirataonline.com.br\",\"vatID\":\"47.621.418\\\/0001-80\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\",\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"pronouns\":\"Ele\",\"description\":\"Desde 2003 trabalhando com not\u00edcias.\",\"sameAs\":[\"http:\\\/\\\/ubirataoline.com.br\",\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/www.instagram.com\\\/ubirataonline_oficial\",\"https:\\\/\\\/x.com\\\/x.com\\\/ubirataonline\"],\"honorificPrefix\":\"Mr.\",\"honorificSuffix\":\"MD\",\"birthDate\":\"1980-06-16\",\"gender\":\"masculino\",\"award\":[\"V\u00e1rios pr\u00eamios de melhor portal da cidade\"],\"jobTitle\":\"Diretor\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/author\\\/ubirataonline\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#local-main-place-address\",\"streetAddress\":\"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista\",\"addressLocality\":\"UBIRATA\",\"postalCode\":\"85440-000\",\"addressRegion\":\"PR\",\"addressCountry\":\"BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"width\":500,\"height\":500,\"caption\":\"Ubirat\u00e3 Online Not\u00edcias\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"UBIRATA\" \/>\n<meta name=\"geo.position\" content=\"-24.5361401;-52.9921776\" \/>\n<meta name=\"geo.region\" content=\"Brazil\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","description":"Toluca enfrenta la 'maldici\u00f3n' que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ubirataonline.com.br\/en\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/","og_locale":"en_US","og_type":"article","og_title":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf","og_description":"Toluca enfrenta la 'maldici\u00f3n' que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la","og_url":"https:\/\/ubirataonline.com.br\/en\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/","og_site_name":"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","article_publisher":"https:\/\/www.facebook.com\/portalubirataonline","article_author":"https:\/\/www.facebook.com\/portalubirataonline","article_published_time":"2026-05-07T03:54:21+00:00","article_modified_time":"2026-05-07T03:54:30+00:00","og_image":[{"width":1296,"height":729,"url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg","type":"image\/jpeg"}],"author":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","twitter_card":"summary_large_image","twitter_creator":"@x.com\/ubirataonline","twitter_site":"@ubirataonline","twitter_misc":{"Written by":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#article","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/"},"author":{"name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c"},"headline":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf","datePublished":"2026-05-07T03:54:21+00:00","dateModified":"2026-05-07T03:54:30+00:00","mainEntityOfPage":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/"},"wordCount":506,"publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"image":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg","keywords":["bicampeones","clubes","Concacaf","ganan","liga","Toluca"],"articleSection":["Ubirat\u00e3"],"inLanguage":"en-US","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/ubirataonline.com.br\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/","url":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/","name":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#primaryimage"},"image":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg","datePublished":"2026-05-07T03:54:21+00:00","dateModified":"2026-05-07T03:54:30+00:00","description":"Toluca enfrenta la 'maldici\u00f3n' que ha perseguido a Pumas, Le\u00f3n, Atlas y Am\u00e9rica: la incapacidad de los bicampeones mexicanos para coronarse en la","breadcrumb":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#primaryimage","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/Toluca-Clubes-bicampeones-de-Liga-MX-no-ganan-Concacaf.jpeg","width":1296,"height":729,"caption":"Mohamed revela que contar\u00e1 con Gallardo y Vega en la Concachampions (1:01)Alexis Vega y Jes\u00fas Gallardo podr\u00e1n jugar con Toluca el partido de vuelta de las semifinales de Concacaf Champions Cup ante LAFC, debido a que recibieron permiso de la Selecci\u00f3n Mexicana. (1:01)"},{"@type":"BreadcrumbList","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ubirataonline.com.br\/"},{"@type":"ListItem","position":2,"name":"Toluca: Clubes bicampeones de Liga MX no ganan Concacaf"}]},{"@type":"WebSite","@id":"https:\/\/ubirataonline.com.br\/#website","url":"https:\/\/ubirataonline.com.br\/","name":"Ubirat\u00e3 Online Not\u00edcias","description":"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.","publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"alternateName":"Ubirat\u00e3 Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ubirataonline.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/ubirataonline.com.br\/#organization","name":"Ubirat\u00e3 Online Not\u00edcias","alternateName":"Ubirat\u00e3 Online","url":"https:\/\/ubirataonline.com.br\/","logo":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#local-main-organization-logo"},"image":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/portalubirataonline","https:\/\/x.com\/ubirataonline","https:\/\/mastodon.social\/@ubirataonline","https:\/\/www.facebook.com\/groups\/311144672285604","https:\/\/www.facebook.com\/UBTAOnline","https:\/\/www.instagram.com\/portalubirataonline\/","https:\/\/twitter.com\/ubirataonline"],"description":"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.","legalName":"UBIRATA ONLINE NOT\u00cdCIAS","foundingDate":"2009-01-05","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/ubirataonline.com.br\/faq\/","address":{"@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"-24.5361401","longitude":"-52.9921776"},"telephone":["+5544998308235"],"contactPoint":{"@type":"ContactPoint","email":"contato@ubirataonline.com.br"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"contato@ubirataonline.com.br","vatID":"47.621.418\/0001-80"},{"@type":"Person","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c","name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","pronouns":"Ele","description":"Desde 2003 trabalhando com not\u00edcias.","sameAs":["http:\/\/ubirataoline.com.br","https:\/\/www.facebook.com\/portalubirataonline","https:\/\/www.instagram.com\/ubirataonline_oficial","https:\/\/x.com\/x.com\/ubirataonline"],"honorificPrefix":"Mr.","honorificSuffix":"MD","birthDate":"1980-06-16","gender":"masculino","award":["V\u00e1rios pr\u00eamios de melhor portal da cidade"],"jobTitle":"Diretor","url":"https:\/\/ubirataonline.com.br\/en\/author\/ubirataonline\/"},{"@type":"PostalAddress","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#local-main-place-address","streetAddress":"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista","addressLocality":"UBIRATA","postalCode":"85440-000","addressRegion":"PR","addressCountry":"BR"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/toluca-clubes-bicampeones-de-liga-mx-no-ganan-concacaf\/#local-main-organization-logo","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","width":500,"height":500,"caption":"Ubirat\u00e3 Online Not\u00edcias"}]},"geo.placename":"UBIRATA","geo.position":{"lat":"-24.5361401","long":"-52.9921776"},"geo.region":"Brazil"},"_links":{"self":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/123001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/comments?post=123001"}],"version-history":[{"count":0,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/123001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media\/123002"}],"wp:attachment":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media?parent=123001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/categories?post=123001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/tags?post=123001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}