{"id":164360,"date":"2026-08-11T14:09:20","date_gmt":"2026-08-11T17:09:20","guid":{"rendered":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/"},"modified":"2026-08-11T14:09:20","modified_gmt":"2026-08-11T17:09:20","slug":"petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras","status":"publish","type":"post","link":"https:\/\/ubirataonline.com.br\/en\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/","title":{"rendered":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras"},"content":{"rendered":"<p>A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no fortalecimento da Petrobras e no aumento do controle estatal sobre a empresa. Entre as principais reivindica\u00e7\u00f5es est\u00e1 a redu\u00e7\u00e3o do pagamento de dividendos aos acionistas para priorizar o interesse p\u00fablico, segundo documentos divulgados pela Federa\u00e7\u00e3o.<\/p>\n<p>O grupo tamb\u00e9m defende a reestatiza\u00e7\u00e3o de refinarias privatizadas nos \u00faltimos anos e a reinstitui\u00e7\u00e3o da obrigatoriedade da Petrobras como operadora \u00fanica no regime de partilha em \u00e1reas do pr\u00e9-sal, conforme a Lei n\u00ba 12.351 de 2010, revogada parcialmente pela Lei n\u00ba 13.365 de 2016. Essas medidas buscam garantir maior dom\u00ednio da estatal na explora\u00e7\u00e3o e produ\u00e7\u00e3o de petr\u00f3leo no pa\u00eds.<\/p>\n<h3>Refor\u00e7o no papel da Petrobras e mudan\u00e7as na governan\u00e7a<\/h3>\n<p>A FUP prop\u00f5e ampliar a participa\u00e7\u00e3o acion\u00e1ria do Estado na Petrobras e reformar sua governan\u00e7a para reverter o direcionamento da empresa \u00e0 maximiza\u00e7\u00e3o e distribui\u00e7\u00e3o de lucros em curto prazo, que favorece acionistas. Recomenda-se uma revis\u00e3o do Estatuto Social da companhia e o ajuste da pol\u00edtica de remunera\u00e7\u00e3o aos acionistas, estabelecendo como limite 25% do lucro l\u00edquido, conforme a Lei das Sociedades An\u00f4nimas, para priorizar o interesse p\u00fablico.<\/p>\n<h3>Distribui\u00e7\u00e3o justa dos recursos e cria\u00e7\u00e3o de fundos<\/h3>\n<p>Entre as propostas estruturadas pela FUP est\u00e1 a cria\u00e7\u00e3o de um comit\u00ea para gest\u00e3o da renda petrol\u00edfera, destinado a definir objetivos para fundos como o do Pr\u00e9-sal e do Clima. A Federa\u00e7\u00e3o defende tamb\u00e9m a cria\u00e7\u00e3o do Fundo Estabiliza Brasil, para mitigar a volatilidade no mercado de petr\u00f3leo, e do Fundo para a Transi\u00e7\u00e3o Energ\u00e9tica. Al\u00e9m disso, sugere a institui\u00e7\u00e3o de um imposto permanente sobre a exporta\u00e7\u00e3o de petr\u00f3leo cru para incentivar o refino nacional e tributo sobre lucros extraordin\u00e1rios para financiar a transi\u00e7\u00e3o.<\/p>\n<h3>Transi\u00e7\u00e3o energ\u00e9tica e desenvolvimento sustent\u00e1vel<\/h3>\n<p>A plataforma inclui ainda diretrizes para uma transi\u00e7\u00e3o energ\u00e9tica que considere o ser humano, o combate \u00e0 pobreza energ\u00e9tica e o meio ambiente de forma integrada. Prop\u00f5e-se maior participa\u00e7\u00e3o social e sindical na formula\u00e7\u00e3o dessas pol\u00edticas, al\u00e9m do desenvolvimento de um Programa Nacional de Adapta\u00e7\u00e3o \u00e0s Mudan\u00e7as do Clima. O setor de \u00f3leo e g\u00e1s, respons\u00e1vel por 45% da demanda interna de energia e cerca de 13% do PIB, deve ter seu papel nacional e social respeitado durante essa transi\u00e7\u00e3o, destaca a FUP.<\/p>\n<h2>Frequently asked questions<\/h2>\n<h3>Quais s\u00e3o os principais objetivos das propostas da FUP para a Petrobras?<\/h3>\n<p>Fortalecer o papel estatal, retomar a obrigatoriedade da Petrobras como operadora \u00fanica no pr\u00e9-sal, reestatizar refinarias e limitar os dividendos pagos a acionistas para priorizar o interesse p\u00fablico.<\/p>\n<h3>O que a FUP sugere em rela\u00e7\u00e3o \u00e0 transi\u00e7\u00e3o energ\u00e9tica no Brasil?<\/h3>\n<p>Defende uma transi\u00e7\u00e3o que considere o desenvolvimento nacional, a inclus\u00e3o social, o combate \u00e0 pobreza energ\u00e9tica e a prote\u00e7\u00e3o ambiental de forma integrada, com participa\u00e7\u00e3o social e sindical nas pol\u00edticas.<\/p>\n<h3>Como a FUP prop\u00f5e garantir uma distribui\u00e7\u00e3o mais justa da riqueza gerada pelo petr\u00f3leo?<\/h3>\n<p>Por meio da cria\u00e7\u00e3o de um comit\u00ea para gerir a renda petrol\u00edfera, fundos espec\u00edficos para estabilizar o mercado e financiar a transi\u00e7\u00e3o energ\u00e9tica, al\u00e9m da implanta\u00e7\u00e3o de tributos sobre exporta\u00e7\u00e3o e lucros extraordin\u00e1rios do setor.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no fortalecimento da Petrobras e no aumento do controle estatal sobre a empresa. Entre as principais reivindica\u00e7\u00f5es est\u00e1 a redu\u00e7\u00e3o do pagamento de dividendos aos acionistas para priorizar o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":164361,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow2JLhCw:productID":"","_gspb_post_css":"","maa_idioma":"","maa_pais":"","footnotes":""},"categories":[43088],"tags":[],"class_list":["post-164360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parana"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!<\/title>\n<meta name=\"description\" content=\"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ubirataonline.com.br\/en\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras\" \/>\n<meta property=\"og:description\" content=\"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ubirataonline.com.br\/en\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/\" \/>\n<meta property=\"og:site_name\" content=\"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-11T17:09:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/logo2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1531\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/ubirataonline\" \/>\n<meta name=\"twitter:site\" content=\"@ubirataonline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/\"},\"author\":{\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\"},\"headline\":\"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras\",\"datePublished\":\"2026-08-11T17:09:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/\"},\"wordCount\":603,\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maaimg-post-164360-20260811-170956.webp\",\"articleSection\":[\"Paran\u00e1\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/\",\"name\":\"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maaimg-post-164360-20260811-170956.webp\",\"datePublished\":\"2026-08-11T17:09:20+00:00\",\"description\":\"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maaimg-post-164360-20260811-170956.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maaimg-post-164360-20260811-170956.webp\",\"width\":1536,\"height\":1024,\"caption\":\"Imagem representando petroleiros apresentam plataforma maior controle estatal e menor repasse de dividendos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ubirataonline.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"description\":\"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"alternateName\":\"Ubirat\u00e3 Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ubirataonline.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"alternateName\":\"Ubirat\u00e3 Online\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/x.com\\\/ubirataonline\",\"https:\\\/\\\/mastodon.social\\\/@ubirataonline\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/311144672285604\",\"https:\\\/\\\/www.facebook.com\\\/UBTAOnline\",\"https:\\\/\\\/www.instagram.com\\\/portalubirataonline\\\/\",\"https:\\\/\\\/twitter.com\\\/ubirataonline\"],\"description\":\"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.\",\"legalName\":\"UBIRATA ONLINE NOT\u00cdCIAS\",\"foundingDate\":\"2009-01-05\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/ubirataonline.com.br\\\/faq\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"-24.5361401\",\"longitude\":\"-52.9921776\"},\"telephone\":[\"+5544998308235\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"contato@ubirataonline.com.br\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"contato@ubirataonline.com.br\",\"vatID\":\"47.621.418\\\/0001-80\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\",\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"pronouns\":\"Ele\",\"description\":\"Desde 2003 trabalhando com not\u00edcias.\",\"sameAs\":[\"http:\\\/\\\/ubirataoline.com.br\",\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/www.instagram.com\\\/ubirataonline_oficial\",\"https:\\\/\\\/x.com\\\/x.com\\\/ubirataonline\"],\"honorificPrefix\":\"Mr.\",\"honorificSuffix\":\"MD\",\"birthDate\":\"1980-06-16\",\"gender\":\"masculino\",\"award\":[\"V\u00e1rios pr\u00eamios de melhor portal da cidade\"],\"jobTitle\":\"Diretor\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/author\\\/ubirataonline\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#local-main-place-address\",\"streetAddress\":\"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista\",\"addressLocality\":\"UBIRATA\",\"postalCode\":\"85440-000\",\"addressRegion\":\"PR\",\"addressCountry\":\"BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"width\":500,\"height\":500,\"caption\":\"Ubirat\u00e3 Online Not\u00edcias\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"UBIRATA\" \/>\n<meta name=\"geo.position\" content=\"-24.5361401;-52.9921776\" \/>\n<meta name=\"geo.region\" content=\"Brazil\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","description":"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ubirataonline.com.br\/en\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/","og_locale":"en_US","og_type":"article","og_title":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras","og_description":"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no","og_url":"https:\/\/ubirataonline.com.br\/en\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/","og_site_name":"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","article_publisher":"https:\/\/www.facebook.com\/portalubirataonline","article_author":"https:\/\/www.facebook.com\/portalubirataonline","article_published_time":"2026-08-11T17:09:20+00:00","og_image":[{"width":1531,"height":418,"url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/logo2026.webp","type":"image\/webp"}],"author":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","twitter_card":"summary_large_image","twitter_creator":"@x.com\/ubirataonline","twitter_site":"@ubirataonline","twitter_misc":{"Written by":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#article","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/"},"author":{"name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c"},"headline":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras","datePublished":"2026-08-11T17:09:20+00:00","mainEntityOfPage":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/"},"wordCount":603,"publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"image":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/08\/maaimg-post-164360-20260811-170956.webp","articleSection":["Paran\u00e1"],"inLanguage":"en-US","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/ubirataonline.com.br\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/","url":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/","name":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#primaryimage"},"image":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/08\/maaimg-post-164360-20260811-170956.webp","datePublished":"2026-08-11T17:09:20+00:00","description":"A Federa\u00e7\u00e3o \u00danica dos Petroleiros (FUP) apresentou nesta ter\u00e7a-feira (11) um conjunto de 50 propostas para o setor de \u00f3leo e g\u00e1s no Brasil, com foco no","breadcrumb":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#primaryimage","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/08\/maaimg-post-164360-20260811-170956.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/08\/maaimg-post-164360-20260811-170956.webp","width":1536,"height":1024,"caption":"Imagem representando petroleiros apresentam plataforma maior controle estatal e menor repasse de dividendos"},{"@type":"BreadcrumbList","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ubirataonline.com.br\/"},{"@type":"ListItem","position":2,"name":"Petroleiros apresentam plataforma por maior controle estatal e menor repasse de dividendos na Petrobras"}]},{"@type":"WebSite","@id":"https:\/\/ubirataonline.com.br\/#website","url":"https:\/\/ubirataonline.com.br\/","name":"Ubirat\u00e3 Online Not\u00edcias","description":"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.","publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"alternateName":"Ubirat\u00e3 Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ubirataonline.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/ubirataonline.com.br\/#organization","name":"Ubirat\u00e3 Online Not\u00edcias","alternateName":"Ubirat\u00e3 Online","url":"https:\/\/ubirataonline.com.br\/","logo":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#local-main-organization-logo"},"image":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/portalubirataonline","https:\/\/x.com\/ubirataonline","https:\/\/mastodon.social\/@ubirataonline","https:\/\/www.facebook.com\/groups\/311144672285604","https:\/\/www.facebook.com\/UBTAOnline","https:\/\/www.instagram.com\/portalubirataonline\/","https:\/\/twitter.com\/ubirataonline"],"description":"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.","legalName":"UBIRATA ONLINE NOT\u00cdCIAS","foundingDate":"2009-01-05","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/ubirataonline.com.br\/faq\/","address":{"@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"-24.5361401","longitude":"-52.9921776"},"telephone":["+5544998308235"],"contactPoint":{"@type":"ContactPoint","email":"contato@ubirataonline.com.br"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"contato@ubirataonline.com.br","vatID":"47.621.418\/0001-80"},{"@type":"Person","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c","name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","pronouns":"Ele","description":"Desde 2003 trabalhando com not\u00edcias.","sameAs":["http:\/\/ubirataoline.com.br","https:\/\/www.facebook.com\/portalubirataonline","https:\/\/www.instagram.com\/ubirataonline_oficial","https:\/\/x.com\/x.com\/ubirataonline"],"honorificPrefix":"Mr.","honorificSuffix":"MD","birthDate":"1980-06-16","gender":"masculino","award":["V\u00e1rios pr\u00eamios de melhor portal da cidade"],"jobTitle":"Diretor","url":"https:\/\/ubirataonline.com.br\/en\/author\/ubirataonline\/"},{"@type":"PostalAddress","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#local-main-place-address","streetAddress":"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista","addressLocality":"UBIRATA","postalCode":"85440-000","addressRegion":"PR","addressCountry":"BR"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/petroleiros-apresentam-plataforma-por-maior-controle-estatal-e-menor-repasse-de-dividendos-na-petrobras\/#local-main-organization-logo","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","width":500,"height":500,"caption":"Ubirat\u00e3 Online Not\u00edcias"}]},"geo.placename":"UBIRATA","geo.position":{"lat":"-24.5361401","long":"-52.9921776"},"geo.region":"Brazil"},"_links":{"self":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/164360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/comments?post=164360"}],"version-history":[{"count":0,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/164360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media\/164361"}],"wp:attachment":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media?parent=164360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/categories?post=164360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/tags?post=164360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}