{"id":169989,"date":"2026-09-02T14:22:43","date_gmt":"2026-09-02T17:22:43","guid":{"rendered":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/"},"modified":"2026-09-02T14:22:43","modified_gmt":"2026-09-02T17:22:43","slug":"tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr","status":"publish","type":"post","link":"https:\/\/ubirataonline.com.br\/en\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/","title":{"rendered":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)"},"content":{"rendered":"<h2>Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edcia<\/h2>\n<p>Tr\u00eas trabalhadores foram resgatados na tarde desta ter\u00e7a-feira (01) ap\u00f3s serem soterrados durante a constru\u00e7\u00e3o de um pr\u00e9dio em Pato Branco, no sudoeste do Paran\u00e1.<\/p>\n<p>segundo G1, um dos oper\u00e1rios conseguiu sair por conta pr\u00f3pria; as outras duas v\u00edtimas precisaram ser retiradas pelo Corpo de Bombeiros. Um dos trabalhadores recebeu atendimento m\u00e9dico e foi levado a uma Unidade de Pronto Atendimento (UPA).<\/p>\n<h3>Relatos do local<\/h3>\n<p>O pedreiro Deusivan de Freitas relatou o susto: <strong>&#8220;N\u00e3o deu nem tempo de agir para sair. Pensei que ia morrer&#8221;<\/strong>.<\/p>\n<p>O capit\u00e3o Melchior Felipe Ferreira dos Santos explicou que uma das v\u00edtimas ficou em um espa\u00e7o protegido pelas pr\u00f3prias escoras da obra: <strong>&#8220;O local onde ele estava era entre escora. Ent\u00e3o as pr\u00f3prias escoras da obra ajudaram a fazer o que a gente chama de espa\u00e7o vital isolado, que permitiu que ele respirasse e tivesse condi\u00e7\u00f5es de sobreviver&#8221;<\/strong>.<\/p>\n<h3>Situa\u00e7\u00e3o do canteiro<\/h3>\n<p>Enquanto os bombeiros conduziam o salvamento, outras equipes avaliaram o risco de um novo deslizamento no local. A obra foi interditada para a realiza\u00e7\u00e3o de per\u00edcia.<\/p>","protected":false},"excerpt":{"rendered":"<p>Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edcia Tr\u00eas trabalhadores foram resgatados na tarde desta ter\u00e7a-feira (01) ap\u00f3s serem soterrados durante a constru\u00e7\u00e3o de um pr\u00e9dio em Pato Branco, no sudoeste do Paran\u00e1. segundo G1, um dos oper\u00e1rios conseguiu sair por conta pr\u00f3pria; as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":169990,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow2JLhCw:productID":"","_gspb_post_css":"","maa_idioma":"","maa_pais":"","footnotes":""},"categories":[43088],"tags":[],"class_list":["post-169989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parana"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR) - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!<\/title>\n<meta name=\"description\" content=\"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ubirataonline.com.br\/en\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)\" \/>\n<meta property=\"og:description\" content=\"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ubirataonline.com.br\/en\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/\" \/>\n<meta property=\"og:site_name\" content=\"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/portalubirataonline\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T17:22:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/logo2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1531\" \/>\n\t<meta property=\"og:image:height\" content=\"418\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@x.com\/ubirataonline\" \/>\n<meta name=\"twitter:site\" content=\"@ubirataonline\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/\"},\"author\":{\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\"},\"headline\":\"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)\",\"datePublished\":\"2026-09-02T17:22:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/maaimg-post-169989-20260902-172302.webp\",\"articleSection\":[\"Paran\u00e1\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/\",\"name\":\"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR) - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/maaimg-post-169989-20260902-172302.webp\",\"datePublished\":\"2026-09-02T17:22:43+00:00\",\"description\":\"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/maaimg-post-169989-20260902-172302.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/maaimg-post-169989-20260902-172302.webp\",\"width\":1536,\"height\":1024,\"caption\":\"Imagem ilustrativa Gerada por IA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ubirataonline.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#website\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"description\":\"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\"},\"alternateName\":\"Ubirat\u00e3 Online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ubirataonline.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#organization\",\"name\":\"Ubirat\u00e3 Online Not\u00edcias\",\"alternateName\":\"Ubirat\u00e3 Online\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/x.com\\\/ubirataonline\",\"https:\\\/\\\/mastodon.social\\\/@ubirataonline\",\"https:\\\/\\\/www.facebook.com\\\/groups\\\/311144672285604\",\"https:\\\/\\\/www.facebook.com\\\/UBTAOnline\",\"https:\\\/\\\/www.instagram.com\\\/portalubirataonline\\\/\",\"https:\\\/\\\/twitter.com\\\/ubirataonline\"],\"description\":\"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.\",\"legalName\":\"UBIRATA ONLINE NOT\u00cdCIAS\",\"foundingDate\":\"2009-01-05\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"},\"publishingPrinciples\":\"https:\\\/\\\/ubirataonline.com.br\\\/faq\\\/\",\"address\":{\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"-24.5361401\",\"longitude\":\"-52.9921776\"},\"telephone\":[\"+5544998308235\"],\"contactPoint\":{\"@type\":\"ContactPoint\",\"email\":\"contato@ubirataonline.com.br\"},\"openingHoursSpecification\":{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"00:00\",\"closes\":\"23:59\"},\"email\":\"contato@ubirataonline.com.br\",\"vatID\":\"47.621.418\\\/0001-80\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/#\\\/schema\\\/person\\\/372f87bbd3fdd79b8556b84c98d0bc1c\",\"name\":\"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO\",\"pronouns\":\"Ele\",\"description\":\"Desde 2003 trabalhando com not\u00edcias.\",\"sameAs\":[\"http:\\\/\\\/ubirataoline.com.br\",\"https:\\\/\\\/www.facebook.com\\\/portalubirataonline\",\"https:\\\/\\\/www.instagram.com\\\/ubirataonline_oficial\",\"https:\\\/\\\/x.com\\\/x.com\\\/ubirataonline\"],\"honorificPrefix\":\"Mr.\",\"honorificSuffix\":\"MD\",\"birthDate\":\"1980-06-16\",\"gender\":\"masculino\",\"award\":[\"V\u00e1rios pr\u00eamios de melhor portal da cidade\"],\"jobTitle\":\"Diretor\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/en\\\/author\\\/ubirataonline\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#local-main-place-address\",\"streetAddress\":\"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista\",\"addressLocality\":\"UBIRATA\",\"postalCode\":\"85440-000\",\"addressRegion\":\"PR\",\"addressCountry\":\"BR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ubirataonline.com.br\\\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"contentUrl\":\"https:\\\/\\\/ubirataonline.com.br\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/logoubirataonline-1.webp\",\"width\":500,\"height\":500,\"caption\":\"Ubirat\u00e3 Online Not\u00edcias\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"UBIRATA\" \/>\n<meta name=\"geo.position\" content=\"-24.5361401;-52.9921776\" \/>\n<meta name=\"geo.region\" content=\"Brazil\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR) - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","description":"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ubirataonline.com.br\/en\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/","og_locale":"en_US","og_type":"article","og_title":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)","og_description":"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na","og_url":"https:\/\/ubirataonline.com.br\/en\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/","og_site_name":"Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","article_publisher":"https:\/\/www.facebook.com\/portalubirataonline","article_author":"https:\/\/www.facebook.com\/portalubirataonline","article_published_time":"2026-09-02T17:22:43+00:00","og_image":[{"width":1531,"height":418,"url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/05\/logo2026.webp","type":"image\/webp"}],"author":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","twitter_card":"summary_large_image","twitter_creator":"@x.com\/ubirataonline","twitter_site":"@ubirataonline","twitter_misc":{"Written by":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#article","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/"},"author":{"name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c"},"headline":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)","datePublished":"2026-09-02T17:22:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/"},"wordCount":227,"publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"image":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/09\/maaimg-post-169989-20260902-172302.webp","articleSection":["Paran\u00e1"],"inLanguage":"en-US","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/ubirataonline.com.br\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/","url":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/","name":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR) - Ubirat\u00e3 Online Not\u00edcias - A realidade ao seu alcance!","isPartOf":{"@id":"https:\/\/ubirataonline.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#primaryimage"},"image":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#primaryimage"},"thumbnailUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/09\/maaimg-post-169989-20260902-172302.webp","datePublished":"2026-09-02T17:22:43+00:00","description":"Um pedreiro saiu sozinho; outros dois foram resgatados pelo Corpo de Bombeiros e a obra foi interditada para per\u00edciaTr\u00eas trabalhadores foram resgatados na","breadcrumb":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#primaryimage","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/09\/maaimg-post-169989-20260902-172302.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/09\/maaimg-post-169989-20260902-172302.webp","width":1536,"height":1024,"caption":"Imagem ilustrativa Gerada por IA"},{"@type":"BreadcrumbList","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ubirataonline.com.br\/"},{"@type":"ListItem","position":2,"name":"Tr\u00eas trabalhadores s\u00e3o resgatados ap\u00f3s soterramento em obra em Pato Branco (PR)"}]},{"@type":"WebSite","@id":"https:\/\/ubirataonline.com.br\/#website","url":"https:\/\/ubirataonline.com.br\/","name":"Ubirat\u00e3 Online Not\u00edcias","description":"Not\u00edcias de Ubirat\u00e3, regi\u00e3o, Brasil e mundo, com informa\u00e7\u00e3o atualizada e compromisso com o leitor.","publisher":{"@id":"https:\/\/ubirataonline.com.br\/#organization"},"alternateName":"Ubirat\u00e3 Online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ubirataonline.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/ubirataonline.com.br\/#organization","name":"Ubirat\u00e3 Online Not\u00edcias","alternateName":"Ubirat\u00e3 Online","url":"https:\/\/ubirataonline.com.br\/","logo":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#local-main-organization-logo"},"image":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/portalubirataonline","https:\/\/x.com\/ubirataonline","https:\/\/mastodon.social\/@ubirataonline","https:\/\/www.facebook.com\/groups\/311144672285604","https:\/\/www.facebook.com\/UBTAOnline","https:\/\/www.instagram.com\/portalubirataonline\/","https:\/\/twitter.com\/ubirataonline"],"description":"Somos um portal de not\u00edcias independente, criado em 5 de janeiro de 2009, com o objetivo de informar, conectar e valorizar a nossa comunidade de Ubirat\u00e3 e toda aregi\u00e3o. Com conte\u00fado atualizado, confi\u00e1vel e relevante, o Ubirat\u00e3 Online \u00e9 o seu espa\u00e7o para ficar por dentro dos principais acontecimentos locais, regionais, Brasil, Mundo e de interesse geral. Nosso compromisso \u00e9 com a verdade, a transpar\u00eancia e o respeito ao leitor.","legalName":"UBIRATA ONLINE NOT\u00cdCIAS","foundingDate":"2009-01-05","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"},"publishingPrinciples":"https:\/\/ubirataonline.com.br\/faq\/","address":{"@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"-24.5361401","longitude":"-52.9921776"},"telephone":["+5544998308235"],"contactPoint":{"@type":"ContactPoint","email":"contato@ubirataonline.com.br"},"openingHoursSpecification":{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"00:00","closes":"23:59"},"email":"contato@ubirataonline.com.br","vatID":"47.621.418\/0001-80"},{"@type":"Person","@id":"https:\/\/ubirataonline.com.br\/#\/schema\/person\/372f87bbd3fdd79b8556b84c98d0bc1c","name":"REDA\u00c7\u00c3O: UBIRAT\u00c3 ONLINE - F\u00c1BIO AUGUSTO CELESTINO","pronouns":"Ele","description":"Desde 2003 trabalhando com not\u00edcias.","sameAs":["http:\/\/ubirataoline.com.br","https:\/\/www.facebook.com\/portalubirataonline","https:\/\/www.instagram.com\/ubirataonline_oficial","https:\/\/x.com\/x.com\/ubirataonline"],"honorificPrefix":"Mr.","honorificSuffix":"MD","birthDate":"1980-06-16","gender":"masculino","award":["V\u00e1rios pr\u00eamios de melhor portal da cidade"],"jobTitle":"Diretor","url":"https:\/\/ubirataonline.com.br\/en\/author\/ubirataonline\/"},{"@type":"PostalAddress","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#local-main-place-address","streetAddress":"Rua dos Coqueiros, 104 - Bairro Boa Vista, Rua dos Coqueiros, 104 Bairro Boa Vista","addressLocality":"UBIRATA","postalCode":"85440-000","addressRegion":"PR","addressCountry":"BR"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ubirataonline.com.br\/tres-trabalhadores-sao-resgatados-apos-soterramento-em-obra-em-pato-branco-pr\/#local-main-organization-logo","url":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","contentUrl":"https:\/\/ubirataonline.com.br\/wp-content\/uploads\/2026\/06\/logoubirataonline-1.webp","width":500,"height":500,"caption":"Ubirat\u00e3 Online Not\u00edcias"}]},"geo.placename":"UBIRATA","geo.position":{"lat":"-24.5361401","long":"-52.9921776"},"geo.region":"Brazil"},"_links":{"self":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/169989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/comments?post=169989"}],"version-history":[{"count":0,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/posts\/169989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media\/169990"}],"wp:attachment":[{"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/media?parent=169989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/categories?post=169989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ubirataonline.com.br\/en\/wp-json\/wp\/v2\/tags?post=169989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}